{"id":122004,"date":"2026-07-14T18:23:29","date_gmt":"2026-07-15T00:23:29","guid":{"rendered":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/?p=122004"},"modified":"2026-07-14T18:23:30","modified_gmt":"2026-07-15T00:23:30","slug":"adolescente-es-trasladado-al-hospital-luego-de-ser-rescatado-en-la-rayita","status":"publish","type":"post","link":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/adolescente-es-trasladado-al-hospital-luego-de-ser-rescatado-en-la-rayita\/","title":{"rendered":"Adolescente es trasladado al hospital luego de ser rescatado en La Rayita"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">14 de julio de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un operativo de rescate fue desplegado por elementos de Protecci\u00f3n Civil de Santa Catarina para auxiliar a un adolescente de 13 a\u00f1os que result\u00f3 lesionado luego de caer en la zona conocida como La Rayita, ubicada en La Huasteca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al arribar al lugar tras el reporte de emergencia, personal de Jaguares brind\u00f3 atenci\u00f3n prehospitalaria al menor, quien presentaba una herida de aproximadamente cinco cent\u00edmetros con hemorragia activa, adem\u00e1s de una probable fractura en la extremidad superior izquierda y una posible lesi\u00f3n en la regi\u00f3n de la pelvis o cadera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la valoraci\u00f3n, los rescatistas confirmaron que el paciente permanec\u00eda consciente y orientado, y se\u00f1alaron que las lesiones sufridas no representan un riesgo para su vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de estabilizarlo en el sitio, elementos de Jaguares, con apoyo de personal de la Cruz Roja, efectuaron las maniobras necesarias para descender al adolescente de forma segura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez concluido el rescate, el menor fue trasladado a un hospital, donde continuar\u00e1 recibiendo la atenci\u00f3n m\u00e9dica correspondiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>14 de julio de 2026 Un operativo de rescate fue desplegado por elementos de Protecci\u00f3n Civil de Santa Catarina para auxiliar a un adolescente de 13 a\u00f1os que result\u00f3 lesionado luego de caer en la zona conocida como La Rayita, ubicada en La Huasteca. Al arribar al lugar tras el reporte de emergencia, personal de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":122005,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-122004","post","type-post","status-publish","format-link","has-post-thumbnail","hentry","category-locales","post_format-post-format-link","has-thumb"],"_links":{"self":[{"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/posts\/122004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=122004"}],"version-history":[{"count":1,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/posts\/122004\/revisions"}],"predecessor-version":[{"id":122006,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/posts\/122004\/revisions\/122006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/media\/122005"}],"wp:attachment":[{"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=122004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=122004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsemanariodenuevoleon.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=122004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}